{"id":5499,"date":"2017-04-18T16:49:51","date_gmt":"2017-04-18T14:49:51","guid":{"rendered":"https:\/\/www.uhrinstinkt.de\/magazin\/?p=5499"},"modified":"2019-03-08T11:57:34","modified_gmt":"2019-03-08T10:57:34","slug":"oris-baselworld-2017","status":"publish","type":"post","link":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/","title":{"rendered":"Oris auf der Baselworld 2017"},"content":{"rendered":"<h2>\u00abRetro-Fliegeruhr und Taucher-Neuheiten feiern neben der Oris 110 Years Limited Edition Premiere\u00bb<\/h2>\n<p style=\"text-align: justify;\"><strong>Oris z\u00e4hlt zu den relativ wenigen Schweizer Uhrenherstellern, die sich bis heute ihre Unabh\u00e4ngigkeit bewahren konnten. Bis heute befindet sich das Unternehmen in privater Hand und ist nicht Teil eines gro\u00dfen Konzerns mit mehreren verschiedenen Marken. Zur Baselworld 2017 pr\u00e4sentierte die vor allem f\u00fcr ihre Taucher- und Fliegeruhren bekannte Marke mehrere Neuheiten, die zum Teil an die Jubil\u00e4umsmodelle des Jahres 2014 ankn\u00fcpfen.<\/strong><\/p>\n<h2>Update f\u00fcr die Taucheruhren-Linie<\/h2>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.uhrinstinkt.de\/uhren\/oris\/diving\/\">Oris Taucheruhren der Aquis-Kollektion<\/a><\/span> z\u00e4hlen zu den bekanntesten Modellen der Marke. Sie erfreuen ihre Liebhaber nicht zuletzt dadurch, dass sie in einem Marktsegment mit vielen optisch relativ \u00e4hnlichen Modellen durchaus eine bemerkenswerte Eigenst\u00e4ndigkeit und einen hohen Wiedererkennungswert aufweisen.<\/p>\n<p style=\"text-align: justify;\">Anl\u00e4sslich der Baselworld 2017 bescherte der Hersteller seiner Taucheruhrenlinie ein Update, das ihren Modellen vor allem mehr Eleganz verleiht und sie zugleich moderner wirken l\u00e4sst.<\/p>\n<h3>Aquis auf dem Zifferblatt<\/h3>\n<p style=\"text-align: justify;\">Die charakteristischen Merkmale der Kollektion sind dabei aber erhalten geblieben. Die Bandanst\u00f6\u00dfe haben ihre Breite behalten, sind nun aber etwas flacher. Die gro\u00dfz\u00fcgig mit Leuchtmasse versehenen Indizes und Zeiger wirken im Vergleich zu den Vorg\u00e4ngerversionen markanter, doch die auff\u00e4lligste Neuerung auf dem Zifferblatt d\u00fcrfte der Name Aquis sein, der nun erstmals dort zu lesen ist. Zu den Eigenschaften, die unver\u00e4ndert beibehalten wurden, z\u00e4hlen neben der guten Ablesbarkeit bei Dunkelheit die Taucher-L\u00fcnette aus kratzfester Keramik sowie die Wasserdichtigkeit bis zu 300 Metern.<\/p>\n<div class=\"BorlabsCookie _brlbs-cb-youtube\"><div class=\"_brlbs-content-blocker\"> <div class=\"_brlbs-embed _brlbs-video-youtube\"> <img class=\"_brlbs-thumbnail\" src=\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/plugins\/borlabs-cookie\/assets\/images\/cb-no-thumbnail.png\" alt=\"YouTube\"> <div class=\"_brlbs-caption\"> <p>Mit dem Laden des Videos akzeptieren Sie die Datenschutzerkl\u00e4rung von YouTube.<br><a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Mehr erfahren<\/a><\/p> <p><a class=\"_brlbs-btn _brlbs-icon-play-white\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Video laden<\/a><\/p> <p><label><input type=\"checkbox\" name=\"unblockAll\" value=\"1\" checked> <small>YouTube immer entsperren<\/small><\/label><\/p> <\/div> <\/div> <\/div><div class=\"borlabs-hide\" data-borlabs-cookie-type=\"content-blocker\" data-borlabs-cookie-id=\"youtube\"><script type=\"text\/template\">PHA+PGlmcmFtZSBsb2FkaW5nPSJsYXp5IiBzcmM9Imh0dHBzOi8vd3d3LnlvdXR1YmUtbm9jb29raWUuY29tL2VtYmVkLzFyVEdZd0V4dHR3P3JlbD0wIiB3aWR0aD0iNjQwIiBoZWlnaHQ9IjM2MCIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbj0iYWxsb3dmdWxsc2NyZWVuIj48L2lmcmFtZT48L3A+<\/script><\/div><\/div>\n<p style=\"text-align: justify;\">Das Edelstahlgeh\u00e4use der neuen Aquis Date hat einen Durchmesser von 43,5 Millimetern, und in seinem Inneren arbeitet ein modifiziertes Automatikwerk vom Kaliber Sellita SW200, das von Oris unter der Bezeichnung Cal. 733 gef\u00fchrt wird. Das Zifferblatt wirkt dank dem bei der Sechs statt bei der Drei positionierten Datumsfenster angenehm ruhig und symmetrisch; es ist in mehreren Farbvarianten erh\u00e4ltlich. Bei den Armb\u00e4ndern haben die Kunden die Wahl zwischen Kautschuk, Leder und Edelstahl.<\/p>\n<h3><a href=\"https:\/\/www.uhrinstinkt.de\/oris-aquis-depth-gauge-chrono-01-774-7708-4154-set-rs.html\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5510 size-full alignright\" title=\"Oris Aquis Depth Gauge | Version: 01 774 7708 4154-Set RS\" src=\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Aquis-Depth-Gauge-Version-01-774-7708-4154-Set-RS.jpg\" alt=\"Oris Aquis Depth Gauge Version 01 774 7708 4154-Set RS\" width=\"266\" height=\"355\" srcset=\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Aquis-Depth-Gauge-Version-01-774-7708-4154-Set-RS.jpg 266w, https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Aquis-Depth-Gauge-Version-01-774-7708-4154-Set-RS-225x300.jpg 225w\" sizes=\"auto, (max-width: 266px) 100vw, 266px\" \/><\/a>Aquis Depth Gauge<\/h3>\n<p style=\"text-align: justify;\">Berufstaucher und ambitionierte Sporttaucher finden im Post-Baselworld-Sortiment von Oris mit der Aquis Depth Gauge \u00fcbrigens noch ein weiteres interessantes Modell mit einem noch gr\u00f6\u00dferen Einsatzbereich unter Wasser. Denn die Aquis Depth Gauge ist eine Taucheruhr, die nicht nur bis zu 500 Metern wasserdicht, sondern au\u00dferdem noch mit einem Tiefenmesser ausgestattet ist und somit h\u00f6chste professionelle Anspr\u00fcche erf\u00fcllt. 2015 stellte der Hersteller dem bereits im Jahr 2013 lancierten Drei-Zeiger-Modell als Weiterentwicklung noch das Modell Aquis Depth Gauge Chronograph an die Seite, welches ebenfalls \u00fcber einen Tiefenmesser nach dem Boyle-Mariotte-Prinzip verf\u00fcgt.<\/p>\n<p style=\"text-align: justify;\">Dieser funktioniert ebenso einfach wie genial: Durch einen kleinen Kanal im Uhrglas kann Wasser eindringen und die darin befindliche Luft zusammenpressen. Dadurch wird die am Rand des Zifferblatts sichtbare Tiefenskala so weit bewegt, dass die aktuelle Tiefenangabe in Metern oben bei der Zw\u00f6lf angezeigt wird.<\/p>\n<h2>Crown ProPilot Altimeter: das Pendant zur Depth Gauge f\u00fcr Piloten<\/h2>\n<p style=\"text-align: justify;\">Wer von dieser zus\u00e4tzlichen Funktion fasziniert ist, sich aber h\u00e4ufiger \u00fcber den Wolken als unter Wasser aufh\u00e4lt, sollte sich statt einer Aquis lieber das Gegenst\u00fcck f\u00fcr Piloten ansehen. Die <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.uhrinstinkt.de\/uhren\/oris\/aviation\/big-crown-propilot\/\">Big Crown ProPilot Altimeter<\/a><\/span> ist \u2013 entsprechend ihrem Einsatzzweck \u2013 statt eines Tiefenmessers mit einem mechanischen H\u00f6henmesser ausgestattet, der die jeweilige H\u00f6he auf Basis des Luftdrucks anzeigt \u2013 und das nicht erst seit der Baselworld 2017.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.uhrinstinkt.de\/oris-big-crown-propilot-gmt-small-second-01-748-7710-4063-07-5-22-06fc.html\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5518 size-full alignleft\" title=\"Oris Big Crown ProPilot GMT Small Second | Version: 01 748 7710 4063-07 5 22 06FC\" src=\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Big-Crown-ProPilot-GMT-Small-Second-Version-01-748-7710-4063-07-5-22-06FC.jpg\" alt=\"Oris Big Crown ProPilot GMT Small Second Version 01 748 7710 4063-07 5 22 06FC\" width=\"229\" height=\"355\" srcset=\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Big-Crown-ProPilot-GMT-Small-Second-Version-01-748-7710-4063-07-5-22-06FC.jpg 229w, https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Big-Crown-ProPilot-GMT-Small-Second-Version-01-748-7710-4063-07-5-22-06FC-194x300.jpg 194w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/><\/a>Da sich der Luftdruck ver\u00e4ndert, muss der H\u00f6henmesser unter Umst\u00e4nden kalibriert werden, um m\u00f6glichst exakte Messwerte zu liefern, daf\u00fcr braucht er jedoch keine Batterie und kommt ohne jede Elektronik aus.<\/p>\n<p style=\"text-align: justify;\">Ein reizvoller Nebeneffekt ist die Tatsache, dass sich der H\u00f6henmesser indirekt auch als Barometer verwenden l\u00e4sst und damit zumindest eine ungef\u00e4hre Wetterindikation geben kann. Eine gewisse technische Herausforderung bestand darin, die Uhr trotz der auf Luftdruck reagierenden H\u00f6henmesserfunktion wasserdicht zu bekommen.<\/p>\n<p style=\"text-align: justify;\">Oris l\u00f6ste das Problem dadurch, dass sich die Krone bei Bedarf \u2013 etwa vor dem Baden gehen \u2013 ganz verschrauben l\u00e4sst.<\/p>\n<p style=\"text-align: justify;\">Dann sind zwar vor\u00fcbergehend keine H\u00f6henmessungen m\u00f6glich, doch kann das Wasser dem Innenleben der Uhr nichts anhaben. Die H\u00f6he ist wahlweise in Metern oder in Fu\u00df ablesbar, und bei der Drei findet sich zudem noch ein kleines Fenster zur Anzeige des Tagesdatums.<\/p>\n<h3><a href=\"https:\/\/www.uhrinstinkt.de\/oris-big-crown-propilot-chronograph-01-774-7699-4063-07-8-22-19.html\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-5533 size-full\" title=\"Oris Big Crown ProPilot Chronograph | Version: 01 774 7699 4063-07 8 22 19\" src=\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Big-Crown-ProPilot-Chronograph-Version-01-774-7699-4063-07-8-22-19.jpg\" alt=\"Oris Big Crown ProPilot Chronograph Version 01 774 7699 4063-07 8 22 19\" width=\"235\" height=\"360\" srcset=\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Big-Crown-ProPilot-Chronograph-Version-01-774-7699-4063-07-8-22-19.jpg 235w, https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Big-Crown-ProPilot-Chronograph-Version-01-774-7699-4063-07-8-22-19-196x300.jpg 196w\" sizes=\"auto, (max-width: 235px) 100vw, 235px\" \/><\/a>Zwei Fliegeruhren mit Tradition feiern auf der Baselworld Premiere<\/h3>\n<p style=\"text-align: justify;\">Mit der Big Crown ProPilot Altimeter kn\u00fcpfte der Hersteller \u00fcbrigens an eine mittlerweile rund 100-j\u00e4hrige <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.uhrinstinkt.de\/uhren\/oris\/aviation\/\">Oris Fliegeruhren<\/a><\/span>-Tradition im eigenen Haus an, die anl\u00e4sslich der Baselworld 2017 durch zwei weitere Modelle fortgef\u00fchrt wurde. Mit einem abgerundeten Edelstahlgeh\u00e4use, vergr\u00f6\u00dferten arabischen Ziffern, etwas mehr Superluminova und einer griffigeren Krone versehen, heben sich beide dezent von ihren Vorg\u00e4ngern ab. K\u00e4ufer haben die Wahl zwischen der stattlichen Big Crown ProPilot GMT Small Second mit Anzeige einer zweiten Zeitzone und stattlichen 45 Millimetern Geh\u00e4usedurchmesser und der Big Crown ProPilot Chronograph.<\/p>\n<p style=\"text-align: justify;\">Beide Uhren werden von Automatikwerken angetrieben und verf\u00fcgen \u00fcber einen Glasboden.<\/p>\n<h2>Baselworld 2017: 110 Years Limited Edition f\u00fcr traditionsbewusste Oris-Fans<\/h2>\n<p style=\"text-align: justify;\">Dass dem Hersteller die eigene Tradition am Herzen liegt, war bereits zum 110. Gr\u00fcndungsjubil\u00e4um der Firma im Jahr 2014 deutlich geworden, als die Oris 110 Years Limited Edition nach rund zehnj\u00e4hriger Entwicklungsarbeit zum ersten Mal der \u00d6ffentlichkeit pr\u00e4sentiert wurde. Dabei hatte sich gezeigt, dass die Oris 110 Years Limited Edition nicht nur ein Beispiel liebevoller Traditionspflege ist, sondern zugleich einen innovativen Meilenstein der Unternehmensgeschichte darstellt. Denn mit dem Kaliber 110 erhielt dieses Modell zum ersten Mal seit 35 Jahren wieder ein komplett im eigenen Haus konzipiertes mechanisches Werk. Dieses verf\u00fcgte \u00fcber einen Handaufzug und eine maximale Gangreserve von beachtlichen zehn Tagen, kombiniert mit einer nicht-linearen Gangreserveanzeige.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.uhrinstinkt.de\/oris-air-racing-edition-vi-limited-edition-01-752-7698-4284-set.html\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-5544 size-full\" title=\"Oris Air Racing Edition VI Limited Edition | Version: 01 752 7698 4284-Set\" src=\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Air-Racing-Edition-VI-Limited-Edition-Version-01-752-7698-4284-Set.jpg\" alt=\"Oris Air Racing Edition VI Limited Edition Version 01 752 7698 4284-Set\" width=\"277\" height=\"360\" srcset=\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Air-Racing-Edition-VI-Limited-Edition-Version-01-752-7698-4284-Set.jpg 277w, https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Air-Racing-Edition-VI-Limited-Edition-Version-01-752-7698-4284-Set-231x300.jpg 231w\" sizes=\"auto, (max-width: 277px) 100vw, 277px\" \/><\/a>Drei Jahre nach dem Erscheinen der 110 Years Limited Edition folgte nun auf der Baselworld mit der Oris Big Crown 1917 Limited Edition ein weiteres Modell f\u00fcr traditionsbewusste Fans der Marke, die \u00fcbrigens nach einem in der N\u00e4he des H\u00f6lsteiner Firmensitzes flie\u00dfenden Bach benannt ist. Die Big Crown 1917 Limited Edition, von der lediglich 1.917 Exemplare hergestellt werden, wird in klassischer Weise an einem braunen Lederarmband mit Edelstahlschlie\u00dfe getragen. Ihre Form und die nostalgische Typographie der arabischen Ziffern lassen noch erahnen, dass die ersten Fliegeruhren im Prinzip nichts anderes waren als Taschenuhren, die man mit einem Armband sowie einer gro\u00dfen, auch mit Fliegerhandschuhen noch gut bedienbaren Krone ausgestattet hatte. Dabei wirkt das Edelstahlgeh\u00e4use mit einem Durchmesser von 40 Millimetern keinesfalls wuchtig und kommt auch an einem schmaleren Handgelenk gut zur Geltung.<\/p>\n<p style=\"text-align: justify;\">Die nostalgische Anmutung wird zus\u00e4tzlich durch die Beschichtung der Ziffern und Zeiger mit Light Old Radium in einem geblichen Farbton unterstrichen.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.uhrinstinkt.de\/oris-aquis-carlos-coste-limited-edition-iv-01-743-7709-7184-set-rs.html\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-5554 size-full\" title=\"Oris Aquis Small Second Date | Version: 01 743 7709 7184-Set RS\" src=\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Aquis-Small-Second-Date-Version-01-743-7709-7184-Set-RS.jpg\" alt=\"Oris Aquis Small Second Date Version 01 743 7709 7184-Set RS\" width=\"226\" height=\"350\" srcset=\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Aquis-Small-Second-Date-Version-01-743-7709-7184-Set-RS.jpg 226w, https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-Aquis-Small-Second-Date-Version-01-743-7709-7184-Set-RS-194x300.jpg 194w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" \/><\/a>Einen Sekundenzeiger gibt es bei dieser Uhr nicht, denn schlie\u00dflich erinnert sie an eine Zeit, in der selbst Flugzeuge nach heutigen Ma\u00dfst\u00e4ben noch relativ gem\u00e4chlich unterwegs waren. Eine spezielle Gravur auf dem st\u00e4hlernen Geh\u00e4useboden weist diese Uhr als Teil der limitierten Sonderedition aus.<\/p>\n<p style=\"text-align: justify;\">Das mechanische Uhrwerk vom Kaliber 732, das auf dem SW 200-1 basiert, verf\u00fcgt \u00fcber einen automatischen Aufzug mit beidseitig aufziehendem Rotor. Geliefert wird dieses exklusive Retro-Modell zusammen mit einem zweiten Armband in einem stilvollen Lederetui. Verst\u00e4ndlicherweise erhoffen Liebhaber, die auf der Baselworld 2017 bereits einen Blick auf die neuen Modelle erhaschen konnten, dass die <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.uhrinstinkt.de\/uhren\/oris\/\">Oris Uhren<\/a><\/span> schnell in den Onlineshops ankommen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abRetro-Fliegeruhr und Taucher-Neuheiten feiern neben der Oris 110 Years Limited Edition Premiere\u00bb Oris z\u00e4hlt zu den relativ wenigen Schweizer Uhrenherstellern, die sich bis heute ihre Unabh\u00e4ngigkeit bewahren konnten. Bis heute befindet sich das Unternehmen in privater Hand und ist nicht Teil eines gro\u00dfen Konzerns mit mehreren verschiedenen Marken. Zur Baselworld 2017 pr\u00e4sentierte die vor allem &hellip;<\/p>\n","protected":false},"author":1,"featured_media":16078,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[298,308,276,265,309,44,150,118,106],"class_list":["post-5499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuheiten-szene","tag-aquis-date","tag-aquis-depth-gauge","tag-baselworld-2017","tag-chronograph","tag-crown-propilot","tag-fliegeruhren","tag-limited-edition","tag-oris","tag-taucheruhren"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Oris auf der Baselworld 2017 - Uhrinstinkt Magazin<\/title>\n<meta name=\"description\" content=\"Im Uhrinstinkt Magazin von allen Oris Neuheiten auf der Baselworld 2017 erfahren! \u2013 110 Years Limited Edition \u2714 Crown ProPilot Altimeter \u2714 Aquis \u2714\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oris auf der Baselworld 2017 - Uhrinstinkt Magazin\" \/>\n<meta property=\"og:description\" content=\"Im Uhrinstinkt Magazin von allen Oris Neuheiten auf der Baselworld 2017 erfahren! \u2013 110 Years Limited Edition \u2714 Crown ProPilot Altimeter \u2714 Aquis \u2714\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Uhrinstinkt Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uhrinstinkt.de\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-18T14:49:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-08T10:57:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-auf-der-Baselworld-2017-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uhrinstinkt\" \/>\n<meta name=\"twitter:site\" content=\"@uhrinstinkt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/#\/schema\/person\/960ff76add8c05a574d3c3a6800c6965\"},\"headline\":\"Oris auf der Baselworld 2017\",\"datePublished\":\"2017-04-18T14:49:51+00:00\",\"dateModified\":\"2019-03-08T10:57:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/\"},\"wordCount\":1177,\"publisher\":{\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-auf-der-Baselworld-2017-1.jpg\",\"keywords\":[\"Aquis Date\",\"Aquis Depth Gauge\",\"Baselworld 2017\",\"Chronograph\",\"Crown ProPilot\",\"Fliegeruhren\",\"Limited Edition\",\"Oris\",\"Taucheruhren\"],\"articleSection\":[\"Neuheiten &amp; Szene\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/\",\"url\":\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/\",\"name\":\"Oris auf der Baselworld 2017 - Uhrinstinkt Magazin\",\"isPartOf\":{\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-auf-der-Baselworld-2017-1.jpg\",\"datePublished\":\"2017-04-18T14:49:51+00:00\",\"dateModified\":\"2019-03-08T10:57:34+00:00\",\"description\":\"Im Uhrinstinkt Magazin von allen Oris Neuheiten auf der Baselworld 2017 erfahren! \u2013 110 Years Limited Edition \u2714 Crown ProPilot Altimeter \u2714 Aquis \u2714\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#primaryimage\",\"url\":\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-auf-der-Baselworld-2017-1.jpg\",\"contentUrl\":\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-auf-der-Baselworld-2017-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uhrinstinkt.de\/magazin\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oris auf der Baselworld 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/#website\",\"url\":\"https:\/\/www.uhrinstinkt.de\/magazin\/\",\"name\":\"Uhrinstinkt Magazin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uhrinstinkt.de\/magazin\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/#organization\",\"name\":\"Prestige Luxusuhren GmbH\",\"url\":\"https:\/\/www.uhrinstinkt.de\/magazin\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2019\/05\/logo-final-rev.png\",\"contentUrl\":\"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2019\/05\/logo-final-rev.png\",\"width\":250,\"height\":50,\"caption\":\"Prestige Luxusuhren GmbH\"},\"image\":{\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/uhrinstinkt.de\",\"https:\/\/x.com\/uhrinstinkt\",\"http:\/\/www.instagram.com\/uhrinstinkt\/\",\"http:\/\/www.youtube.com\/user\/uhrinstinkt\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/#\/schema\/person\/960ff76add8c05a574d3c3a6800c6965\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.uhrinstinkt.de\/magazin\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a3449097ee9ad77b44f6829fd27ae4c26aee898e18298af72c8ad7de714c38ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a3449097ee9ad77b44f6829fd27ae4c26aee898e18298af72c8ad7de714c38ec?s=96&d=mm&r=g\",\"caption\":\"Admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oris auf der Baselworld 2017 - Uhrinstinkt Magazin","description":"Im Uhrinstinkt Magazin von allen Oris Neuheiten auf der Baselworld 2017 erfahren! \u2013 110 Years Limited Edition \u2714 Crown ProPilot Altimeter \u2714 Aquis \u2714","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/","og_locale":"de_DE","og_type":"article","og_title":"Oris auf der Baselworld 2017 - Uhrinstinkt Magazin","og_description":"Im Uhrinstinkt Magazin von allen Oris Neuheiten auf der Baselworld 2017 erfahren! \u2013 110 Years Limited Edition \u2714 Crown ProPilot Altimeter \u2714 Aquis \u2714","og_url":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/","og_site_name":"Uhrinstinkt Magazin","article_publisher":"https:\/\/www.facebook.com\/uhrinstinkt.de","article_published_time":"2017-04-18T14:49:51+00:00","article_modified_time":"2019-03-08T10:57:34+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-auf-der-Baselworld-2017-1.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@uhrinstinkt","twitter_site":"@uhrinstinkt","twitter_misc":{"Verfasst von":"Admin","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#article","isPartOf":{"@id":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/"},"author":{"name":"Admin","@id":"https:\/\/www.uhrinstinkt.de\/magazin\/#\/schema\/person\/960ff76add8c05a574d3c3a6800c6965"},"headline":"Oris auf der Baselworld 2017","datePublished":"2017-04-18T14:49:51+00:00","dateModified":"2019-03-08T10:57:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/"},"wordCount":1177,"publisher":{"@id":"https:\/\/www.uhrinstinkt.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-auf-der-Baselworld-2017-1.jpg","keywords":["Aquis Date","Aquis Depth Gauge","Baselworld 2017","Chronograph","Crown ProPilot","Fliegeruhren","Limited Edition","Oris","Taucheruhren"],"articleSection":["Neuheiten &amp; Szene"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/","url":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/","name":"Oris auf der Baselworld 2017 - Uhrinstinkt Magazin","isPartOf":{"@id":"https:\/\/www.uhrinstinkt.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#primaryimage"},"image":{"@id":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-auf-der-Baselworld-2017-1.jpg","datePublished":"2017-04-18T14:49:51+00:00","dateModified":"2019-03-08T10:57:34+00:00","description":"Im Uhrinstinkt Magazin von allen Oris Neuheiten auf der Baselworld 2017 erfahren! \u2013 110 Years Limited Edition \u2714 Crown ProPilot Altimeter \u2714 Aquis \u2714","breadcrumb":{"@id":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#primaryimage","url":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-auf-der-Baselworld-2017-1.jpg","contentUrl":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2017\/04\/Oris-auf-der-Baselworld-2017-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.uhrinstinkt.de\/magazin\/oris-baselworld-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uhrinstinkt.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Oris auf der Baselworld 2017"}]},{"@type":"WebSite","@id":"https:\/\/www.uhrinstinkt.de\/magazin\/#website","url":"https:\/\/www.uhrinstinkt.de\/magazin\/","name":"Uhrinstinkt Magazin","description":"","publisher":{"@id":"https:\/\/www.uhrinstinkt.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uhrinstinkt.de\/magazin\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.uhrinstinkt.de\/magazin\/#organization","name":"Prestige Luxusuhren GmbH","url":"https:\/\/www.uhrinstinkt.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.uhrinstinkt.de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2019\/05\/logo-final-rev.png","contentUrl":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-content\/uploads\/2019\/05\/logo-final-rev.png","width":250,"height":50,"caption":"Prestige Luxusuhren GmbH"},"image":{"@id":"https:\/\/www.uhrinstinkt.de\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/uhrinstinkt.de","https:\/\/x.com\/uhrinstinkt","http:\/\/www.instagram.com\/uhrinstinkt\/","http:\/\/www.youtube.com\/user\/uhrinstinkt"]},{"@type":"Person","@id":"https:\/\/www.uhrinstinkt.de\/magazin\/#\/schema\/person\/960ff76add8c05a574d3c3a6800c6965","name":"Admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.uhrinstinkt.de\/magazin\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a3449097ee9ad77b44f6829fd27ae4c26aee898e18298af72c8ad7de714c38ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3449097ee9ad77b44f6829fd27ae4c26aee898e18298af72c8ad7de714c38ec?s=96&d=mm&r=g","caption":"Admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-json\/wp\/v2\/posts\/5499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-json\/wp\/v2\/comments?post=5499"}],"version-history":[{"count":46,"href":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-json\/wp\/v2\/posts\/5499\/revisions"}],"predecessor-version":[{"id":10088,"href":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-json\/wp\/v2\/posts\/5499\/revisions\/10088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-json\/wp\/v2\/media\/16078"}],"wp:attachment":[{"href":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-json\/wp\/v2\/media?parent=5499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-json\/wp\/v2\/categories?post=5499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhrinstinkt.de\/magazin\/wp-json\/wp\/v2\/tags?post=5499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}